{"id":32092,"date":"2019-10-02T14:43:00","date_gmt":"2020-01-21T11:42:57","guid":{"rendered":"https:\/\/cafesnovell.com\/eshop\/uncategorized\/novell-take-away-cup-100cc\/"},"modified":"2023-10-05T17:40:13","modified_gmt":"2023-10-05T15:40:13","slug":"novell-take-away-cup-120cc","status":"publish","type":"product","link":"https:\/\/cafesnovell.com\/en\/producto\/novell-take-away-cup-120cc\/","title":{"rendered":"Novell Take Away Cup"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>NO DEBE APARECER EN .COM<\/p>\n","protected":false},"featured_media":66818,"template":"","meta":{"_acf_changed":false,"content-type":""},"product_brand":[],"product_cat":[172,1252],"product_tag":[],"class_list":{"0":"post-32092","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessories","7":"product_cat-take-away-en","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":null,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novell Take Away Cup - Caf\u00e8s Novell<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cafesnovell.com\/en\/producto\/novell-take-away-cup-120cc\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novell Take Away Cup - Caf\u00e8s Novell\" \/>\n<meta property=\"og:description\" content=\"NO DEBE APARECER EN .COM\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cafesnovell.com\/en\/producto\/novell-take-away-cup-120cc\/\" \/>\n<meta property=\"og:site_name\" content=\"Caf\u00e8s Novell\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-05T15:40:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cafesnovell.com\/wp-content\/uploads\/2019\/10\/vaso-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cafesnovell.com\\\/en\\\/producto\\\/novell-take-away-cup-120cc\\\/\",\"url\":\"https:\\\/\\\/cafesnovell.com\\\/en\\\/producto\\\/novell-take-away-cup-120cc\\\/\",\"name\":\"Novell Take Away Cup - Caf\u00e8s Novell\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cafesnovell.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cafesnovell.com\\\/en\\\/producto\\\/novell-take-away-cup-120cc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cafesnovell.com\\\/en\\\/producto\\\/novell-take-away-cup-120cc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cafesnovell.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/vaso-1.jpg\",\"datePublished\":\"2020-01-21T11:42:57+00:00\",\"dateModified\":\"2023-10-05T15:40:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cafesnovell.com\\\/en\\\/producto\\\/novell-take-away-cup-120cc\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cafesnovell.com\\\/en\\\/producto\\\/novell-take-away-cup-120cc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cafesnovell.com\\\/en\\\/producto\\\/novell-take-away-cup-120cc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cafesnovell.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/vaso-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cafesnovell.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/vaso-1.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cafesnovell.com\\\/en\\\/producto\\\/novell-take-away-cup-120cc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cafesnovell.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/cafesnovell.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Novell Take Away Cup\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cafesnovell.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/cafesnovell.com\\\/en\\\/\",\"name\":\"Caf\u00e8s Novell\",\"description\":\"Organic Premium Coffee\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cafesnovell.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novell Take Away Cup - Caf\u00e8s Novell","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cafesnovell.com\/en\/producto\/novell-take-away-cup-120cc\/","og_locale":"en_US","og_type":"article","og_title":"Novell Take Away Cup - Caf\u00e8s Novell","og_description":"NO DEBE APARECER EN .COM","og_url":"https:\/\/cafesnovell.com\/en\/producto\/novell-take-away-cup-120cc\/","og_site_name":"Caf\u00e8s Novell","article_modified_time":"2023-10-05T15:40:13+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/cafesnovell.com\/wp-content\/uploads\/2019\/10\/vaso-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cafesnovell.com\/en\/producto\/novell-take-away-cup-120cc\/","url":"https:\/\/cafesnovell.com\/en\/producto\/novell-take-away-cup-120cc\/","name":"Novell Take Away Cup - Caf\u00e8s Novell","isPartOf":{"@id":"https:\/\/cafesnovell.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cafesnovell.com\/en\/producto\/novell-take-away-cup-120cc\/#primaryimage"},"image":{"@id":"https:\/\/cafesnovell.com\/en\/producto\/novell-take-away-cup-120cc\/#primaryimage"},"thumbnailUrl":"https:\/\/cafesnovell.com\/wp-content\/uploads\/2019\/10\/vaso-1.jpg","datePublished":"2020-01-21T11:42:57+00:00","dateModified":"2023-10-05T15:40:13+00:00","breadcrumb":{"@id":"https:\/\/cafesnovell.com\/en\/producto\/novell-take-away-cup-120cc\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cafesnovell.com\/en\/producto\/novell-take-away-cup-120cc\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cafesnovell.com\/en\/producto\/novell-take-away-cup-120cc\/#primaryimage","url":"https:\/\/cafesnovell.com\/wp-content\/uploads\/2019\/10\/vaso-1.jpg","contentUrl":"https:\/\/cafesnovell.com\/wp-content\/uploads\/2019\/10\/vaso-1.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/cafesnovell.com\/en\/producto\/novell-take-away-cup-120cc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cafesnovell.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/cafesnovell.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Novell Take Away Cup"}]},{"@type":"WebSite","@id":"https:\/\/cafesnovell.com\/en\/#website","url":"https:\/\/cafesnovell.com\/en\/","name":"Caf\u00e8s Novell","description":"Organic Premium Coffee","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cafesnovell.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"df_price":3.69,"df_sale_price":"","df_regular_price":3.69,"df_image_link":"https:\/\/cafesnovell.com\/wp-content\/uploads\/2019\/10\/vaso-1-300x300.jpg","_links":{"self":[{"href":"https:\/\/cafesnovell.com\/en\/wp-json\/wp\/v2\/product\/32092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cafesnovell.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cafesnovell.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cafesnovell.com\/en\/wp-json\/wp\/v2\/media\/66818"}],"wp:attachment":[{"href":"https:\/\/cafesnovell.com\/en\/wp-json\/wp\/v2\/media?parent=32092"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cafesnovell.com\/en\/wp-json\/wp\/v2\/product_brand?post=32092"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cafesnovell.com\/en\/wp-json\/wp\/v2\/product_cat?post=32092"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cafesnovell.com\/en\/wp-json\/wp\/v2\/product_tag?post=32092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}